{"id":3323,"date":"2025-03-25T13:02:00","date_gmt":"2025-03-25T13:02:00","guid":{"rendered":"https:\/\/www.prudentes.de\/?p=3323"},"modified":"2025-11-20T10:26:14","modified_gmt":"2025-11-20T10:26:14","slug":"podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel","status":"publish","type":"post","link":"https:\/\/www.prudentes.de\/en\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel","title":{"rendered":"Pod\u00adcast: ZAW | Zukunft Auto\u00admo\u00adbil\u00adwirt\u00adschaft mit Ralph Meunzel"},"content":{"rendered":"<p>[et_pb_section fb_built=\"1\" _builder_version=\"4.25.0\" _module_preset=\"default\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"][et_pb_row _builder_version=\"4.25.0\" _module_preset=\"default\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"][et_pb_column type=\"4_4\" _builder_version=\"4.25.0\" _module_preset=\"default\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"][et_pb_heading title=\"ZAW mit Ralph Meunzel - Welche Ver\u00e4nderungen ergeben sich in der Branche durch digitale und soziale Medien?\" _builder_version=\"4.27.4\" _module_preset=\"default\" title_level=\"h2\" title_font=\"||||||||\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\"4.25.0\" _module_preset=\"default\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"][et_pb_column type=\"4_4\" _builder_version=\"4.25.0\" _module_preset=\"default\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"][et_pb_image src=\"https:\/\/www.prudentes.de\/wp-content\/uploads\/2025\/11\/ZAW-Podcast-mit-Ralph-Meunzel_Titelbild.png\" title_text=\"ZAW Podcast mit Ralph Meunzel_Titelbild\" align=\"center\" _builder_version=\"4.27.4\" _module_preset=\"default\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\"4.25.0\" _module_preset=\"default\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"][et_pb_column type=\"4_4\" _builder_version=\"4.25.0\" _module_preset=\"default\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"][et_pb_text _builder_version=\"4.25.0\" _module_preset=\"default\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"]<\/p>\n<p style=\"text-align: justify;\">Willkommen zum Podcast \"Zukunft Automobilwirtschaft\"! Wir sprechen \u00fcber die Zukunft des Automobilhandels und die Themen, die die Branche besch\u00e4ftigen. In unseren Episoden sprechen wir \u00fcber M&amp;A-Prozesse, Nachwuchsf\u00f6rderung, neue Gesch\u00e4ftsmodelle und andere wichtige Themen. Unsere renommierten Interviewpartner teilen ihre Erfahrungen und Einblicke in die Branche und zeigen Strategien f\u00fcr die Herausforderungen der Zukunft auf. Wir laden Sie ein, uns auf dieser spannenden Reise durch die Welt des Automobilhandels zu begleiten.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\"4.27.4\" _module_preset=\"default\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"]<\/p>\n<div class=\"lykOktr3YIn79xOvVQtS\">\n<p class=\"e-91000-text encore-text-body-medium encore-internal-color-text-subdued uSZqU39qytkxgjskgv4n\" data-encore-id=\"text\">In der aktuellen Folge von \"ZAW Zukunft Automobilwirtschaft\" begr\u00fc\u00dfen wir Ralph Meunzel, Chefredakteur und Leiter des renommierten Fachmediums AUTOHAUS.<\/p>\n<p class=\"e-91000-text encore-text-body-medium encore-internal-color-text-subdued uSZqU39qytkxgjskgv4n\" data-encore-id=\"text\">Gemeinsam werfen wir einen fundierten Blick auf die aktuellen Entwicklungen und Herausforderungen im deutschen Automobilhandel. Ralph Meunzel berichtet aus seiner \u00fcber drei Jahrzehnte langen journalistischen T\u00e4tigkeit und teilt seine Einsch\u00e4tzungen zur Zukunft des station\u00e4ren Autohauses. Wir sprechen \u00fcber die Rolle von Omni-Channel-Strategien im Vertrieb und warum die Digitalisierung allein den pers\u00f6nlichen Kontakt zum Kunden nicht ersetzen kann.<\/p>\n<p class=\"e-91000-text encore-text-body-medium encore-internal-color-text-subdued uSZqU39qytkxgjskgv4n\" data-encore-id=\"text\">Wir reden ebenfalls \u00fcber den Einfluss der sozialen Medien auf den Journalismus und die Meinungsbildung. Ralph Meunzel gibt spannende Einblicke, wie sich Medienlandschaften ver\u00e4ndert haben und welchen Stellenwert seri\u00f6ser Fachjournalismus heute noch hat \u2013 oder gerade deshalb wieder gewinnen kann. Zudem diskutieren wir den Einfluss von K\u00fcnstlicher Intelligenz auf die Medien- und Handelslandschaft. Schalten Sie ein und erfahren Sie mehr \u00fcber die spannende Zukunft der Automobilindustrie!<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p class=\"encore-text encore-text-body-medium\" data-encore-id=\"text\" data-slate-node=\"element\" style=\"padding-block-end: 8px;\">[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\"4.27.4\" _module_preset=\"default\" hover_enabled=\"0\" global_colors_info=\"{}\" theme_builder_area=\"post_content\" link_option_url_new_window=\"on\" link_option_url=\"https:\/\/open.spotify.com\/episode\/4F1iLnvZRm3J0mc4684idr?si=c5e04a2988504d96\" sticky_enabled=\"0\"][et_pb_column type=\"4_4\" _builder_version=\"4.25.0\" _module_preset=\"default\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"][et_pb_text _builder_version=\"4.27.4\" _module_preset=\"default\" link_option_url=\"https:\/\/open.spotify.com\/episode\/4F1iLnvZRm3J0mc4684idr?si=c5e04a2988504d96\" link_option_url_new_window=\"on\" hover_enabled=\"0\" global_colors_info=\"{}\" theme_builder_area=\"post_content\" sticky_enabled=\"0\"]<\/p>\n<p><strong><a href=\"https:\/\/open.spotify.com\/episode\/0I4ylQemmQ72NNW7db14v2?si=d0qIzqQsT5qz6pKuuxvZnw\" target=\"_blank\" rel=\"noopener\">Jetzt auf Spotify h\u00f6ren &gt;&gt;<\/a><\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Willkommen zum Podcast \"Zukunft Automobilwirtschaft\"! Wir sprechen \u00fcber die Zukunft des Automobilhandels und die Themen, die die Branche besch\u00e4ftigen. In unseren Episoden sprechen wir \u00fcber M&amp;A-Prozesse, Nachwuchsf\u00f6rderung, neue Gesch\u00e4ftsmodelle und andere wichtige Themen. Unsere renommierten Interviewpartner teilen ihre Erfahrungen und Einblicke in die Branche und zeigen Strategien f\u00fcr die Herausforderungen der Zukunft auf. Wir laden [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3520,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Podcast: ZAW | Zukunft Automobilwirtschaft mit Ralph Meunzel - Prudentes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.prudentes.de\/en\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Podcast: ZAW | Zukunft Automobilwirtschaft mit Ralph Meunzel - Prudentes\" \/>\n<meta property=\"og:description\" content=\"Willkommen zum Podcast &quot;Zukunft Automobilwirtschaft&quot;! Wir sprechen \u00fcber die Zukunft des Automobilhandels und die Themen, die die Branche besch\u00e4ftigen. In unseren Episoden sprechen wir \u00fcber M&amp;A-Prozesse, Nachwuchsf\u00f6rderung, neue Gesch\u00e4ftsmodelle und andere wichtige Themen. Unsere renommierten Interviewpartner teilen ihre Erfahrungen und Einblicke in die Branche und zeigen Strategien f\u00fcr die Herausforderungen der Zukunft auf. Wir laden [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.prudentes.de\/en\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel\/\" \/>\n<meta property=\"og:site_name\" content=\"Prudentes\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-25T13:02:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-20T10:26:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.prudentes.de\/wp-content\/uploads\/2025\/11\/ZAW-Podcast-mit-Ralph-Meunzel_Titelbild-1024x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Prudentes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prudentes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel\"},\"author\":{\"name\":\"Prudentes\",\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/#\\\/schema\\\/person\\\/93b72057083c0c4aa888a2cc8b778587\"},\"headline\":\"Podcast: ZAW | Zukunft Automobilwirtschaft mit Ralph Meunzel\",\"datePublished\":\"2025-03-25T13:02:00+00:00\",\"dateModified\":\"2025-11-20T10:26:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel\"},\"wordCount\":611,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.prudentes.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ZAW-Podcast-mit-Ralph-Meunzel_Titelbild.png\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel\",\"url\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel\",\"name\":\"Podcast: ZAW | Zukunft Automobilwirtschaft mit Ralph Meunzel - Prudentes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.prudentes.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ZAW-Podcast-mit-Ralph-Meunzel_Titelbild.png\",\"datePublished\":\"2025-03-25T13:02:00+00:00\",\"dateModified\":\"2025-11-20T10:26:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/#\\\/schema\\\/person\\\/93b72057083c0c4aa888a2cc8b778587\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel#primaryimage\",\"url\":\"https:\\\/\\\/www.prudentes.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ZAW-Podcast-mit-Ralph-Meunzel_Titelbild.png\",\"contentUrl\":\"https:\\\/\\\/www.prudentes.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ZAW-Podcast-mit-Ralph-Meunzel_Titelbild.png\",\"width\":2069,\"height\":2066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.prudentes.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Podcast: ZAW | Zukunft Automobilwirtschaft mit Ralph Meunzel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/#website\",\"url\":\"https:\\\/\\\/www.prudentes.de\\\/\",\"name\":\"Prudentes\",\"description\":\"Prudentes Management GmbH\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.prudentes.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/#\\\/schema\\\/person\\\/93b72057083c0c4aa888a2cc8b778587\",\"name\":\"Prudentes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/394a838266da979976a9502a8061fc9690356637af29e0726134ddd925513862?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/394a838266da979976a9502a8061fc9690356637af29e0726134ddd925513862?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/394a838266da979976a9502a8061fc9690356637af29e0726134ddd925513862?s=96&d=mm&r=g\",\"caption\":\"Prudentes\"},\"sameAs\":[\"https:\\\/\\\/wordpress.prudentes.de\"],\"url\":\"https:\\\/\\\/www.prudentes.de\\\/en\\\/author\\\/websiteprudentes\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pod\u00adcast: ZAW | Zukunft Auto\u00admo\u00adbil\u00adwirt\u00adschaft mit Ralph Meun\u00adzel \u2014 Prudentes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.prudentes.de\/en\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel\/","og_locale":"en_US","og_type":"article","og_title":"Podcast: ZAW | Zukunft Automobilwirtschaft mit Ralph Meunzel - Prudentes","og_description":"Willkommen zum Podcast \"Zukunft Automobilwirtschaft\"! Wir sprechen \u00fcber die Zukunft des Automobilhandels und die Themen, die die Branche besch\u00e4ftigen. In unseren Episoden sprechen wir \u00fcber M&amp;A-Prozesse, Nachwuchsf\u00f6rderung, neue Gesch\u00e4ftsmodelle und andere wichtige Themen. Unsere renommierten Interviewpartner teilen ihre Erfahrungen und Einblicke in die Branche und zeigen Strategien f\u00fcr die Herausforderungen der Zukunft auf. Wir laden [&hellip;]","og_url":"https:\/\/www.prudentes.de\/en\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel\/","og_site_name":"Prudentes","article_published_time":"2025-03-25T13:02:00+00:00","article_modified_time":"2025-11-20T10:26:14+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.prudentes.de\/wp-content\/uploads\/2025\/11\/ZAW-Podcast-mit-Ralph-Meunzel_Titelbild-1024x1024.png","type":"image\/png"}],"author":"Prudentes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Prudentes","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel#article","isPartOf":{"@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel"},"author":{"name":"Prudentes","@id":"https:\/\/www.prudentes.de\/#\/schema\/person\/93b72057083c0c4aa888a2cc8b778587"},"headline":"Podcast: ZAW | Zukunft Automobilwirtschaft mit Ralph Meunzel","datePublished":"2025-03-25T13:02:00+00:00","dateModified":"2025-11-20T10:26:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel"},"wordCount":611,"commentCount":0,"image":{"@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel#primaryimage"},"thumbnailUrl":"https:\/\/www.prudentes.de\/wp-content\/uploads\/2025\/11\/ZAW-Podcast-mit-Ralph-Meunzel_Titelbild.png","inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel","url":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel","name":"Pod\u00adcast: ZAW | Zukunft Auto\u00admo\u00adbil\u00adwirt\u00adschaft mit Ralph Meun\u00adzel \u2014 Prudentes","isPartOf":{"@id":"https:\/\/www.prudentes.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel#primaryimage"},"image":{"@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel#primaryimage"},"thumbnailUrl":"https:\/\/www.prudentes.de\/wp-content\/uploads\/2025\/11\/ZAW-Podcast-mit-Ralph-Meunzel_Titelbild.png","datePublished":"2025-03-25T13:02:00+00:00","dateModified":"2025-11-20T10:26:14+00:00","author":{"@id":"https:\/\/www.prudentes.de\/#\/schema\/person\/93b72057083c0c4aa888a2cc8b778587"},"breadcrumb":{"@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel#primaryimage","url":"https:\/\/www.prudentes.de\/wp-content\/uploads\/2025\/11\/ZAW-Podcast-mit-Ralph-Meunzel_Titelbild.png","contentUrl":"https:\/\/www.prudentes.de\/wp-content\/uploads\/2025\/11\/ZAW-Podcast-mit-Ralph-Meunzel_Titelbild.png","width":2069,"height":2066},{"@type":"BreadcrumbList","@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralph-meunzel#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.prudentes.de\/"},{"@type":"ListItem","position":2,"name":"Podcast: ZAW | Zukunft Automobilwirtschaft mit Ralph Meunzel"}]},{"@type":"WebSite","@id":"https:\/\/www.prudentes.de\/#website","url":"https:\/\/www.prudentes.de\/","name":"Pru\u00adden\u00adtes","description":"Pru\u00adden\u00adtes Manage\u00adment&nbsp;GmbH","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.prudentes.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.prudentes.de\/#\/schema\/person\/93b72057083c0c4aa888a2cc8b778587","name":"Pru\u00adden\u00adtes","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/394a838266da979976a9502a8061fc9690356637af29e0726134ddd925513862?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/394a838266da979976a9502a8061fc9690356637af29e0726134ddd925513862?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/394a838266da979976a9502a8061fc9690356637af29e0726134ddd925513862?s=96&d=mm&r=g","caption":"Prudentes"},"sameAs":["https:\/\/wordpress.prudentes.de"],"url":"https:\/\/www.prudentes.de\/en\/author\/websiteprudentes"}]}},"_links":{"self":[{"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/posts\/3323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/comments?post=3323"}],"version-history":[{"count":10,"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/posts\/3323\/revisions"}],"predecessor-version":[{"id":3535,"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/posts\/3323\/revisions\/3535"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/media\/3520"}],"wp:attachment":[{"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/media?parent=3323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/categories?post=3323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/tags?post=3323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}