{"id":3290,"date":"2024-04-29T14:19:04","date_gmt":"2024-04-29T14:19:04","guid":{"rendered":"https:\/\/www.prudentes.de\/?p=3290"},"modified":"2024-04-29T14:19:06","modified_gmt":"2024-04-29T14:19:06","slug":"podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein","status":"publish","type":"post","link":"https:\/\/www.prudentes.de\/en\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein","title":{"rendered":"Pod\u00adcast: ZAW | Zukunft Auto\u00admo\u00adbil\u00adwirt\u00adschaft mit Ralf&nbsp;Rhein"},"content":{"rendered":"\n[et_pb_section fb_built=\"1\" theme_builder_area=\"post_content\" _builder_version=\"4.25.0\" _module_preset=\"default\"][et_pb_row _builder_version=\"4.25.0\" _module_preset=\"default\" theme_builder_area=\"post_content\"][et_pb_column _builder_version=\"4.25.0\" _module_preset=\"default\" type=\"4_4\" theme_builder_area=\"post_content\"][et_pb_heading title=\"ZAW mit Ralf Rhein: Von Herausforderungen & chinesischen Playern im etablierten deutschen Automobilhandel - Hype oder Highlight\" _builder_version=\"4.25.0\" _module_preset=\"default\" theme_builder_area=\"post_content\" hover_enabled=\"0\" sticky_enabled=\"0\" title_level=\"h2\" title_font=\"||||||||\"][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\"4.25.0\" _module_preset=\"default\" theme_builder_area=\"post_content\"][et_pb_column _builder_version=\"4.25.0\" _module_preset=\"default\" type=\"4_4\" theme_builder_area=\"post_content\"][et_pb_image src=\"https:\/\/www.prudentes.de\/wp-content\/uploads\/2024\/04\/podcast.jpeg\" _builder_version=\"4.25.0\" _module_preset=\"default\" theme_builder_area=\"post_content\" title_text=\"podcast\" hover_enabled=\"0\" sticky_enabled=\"0\" align=\"center\"][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\"4.25.0\" _module_preset=\"default\" theme_builder_area=\"post_content\"][et_pb_column _builder_version=\"4.25.0\" _module_preset=\"default\" type=\"4_4\" theme_builder_area=\"post_content\"][et_pb_text _builder_version=\"4.25.0\" _module_preset=\"default\" theme_builder_area=\"post_content\" hover_enabled=\"0\" sticky_enabled=\"0\"]<p style=\"text-align: justify;\">Willkommen zum Podcast \"Zukunft Automobilwirtschaft\"! Wir sprechen \u00fcber die Zukunft des Automobilhandels und die Themen, die die Branche besch\u00e4ftigen. In unseren Episoden sprechen wir \u00fcber M&amp;A-Prozesse, Nachwuchsf\u00f6rderung, neue Gesch\u00e4ftsmodelle und andere wichtige Themen. Unsere renommierten Interviewpartner teilen ihre Erfahrungen und Einblicke in die Branche und zeigen Strategien f\u00fcr die Herausforderungen der Zukunft auf. Wir laden Sie ein, uns auf dieser spannenden Reise durch die Welt des Automobilhandels zu begleiten.<\/p>[\/et_pb_text][et_pb_text _builder_version=\"4.25.0\" _module_preset=\"default\" theme_builder_area=\"post_content\" hover_enabled=\"0\" sticky_enabled=\"0\"]<p style=\"text-align: justify;\">In dieser Folge begr\u00fc\u00dfen wir Ralf Rhein, Inhaber der Rhein Gruppe, als unseren Gast. Mit seinem fundierten Branchenwissen gibt Herr Rhein einen umfassenden \u00dcberblick zu den aktuellen Herausforderungen im deutschen Kfz-Gewerbe. Er diskutiert die Umsetzung des Agenturvertriebsmodells, analysiert die Rolle neuer Marktakteure und bewertet den Einfluss von Immobilienfl\u00e4chen auf den Automobilvertrieb. Besonderes Augenmerk legt er auf die zentrale Rolle qualifizierter Beratung im Zeitalter von Elektromobilit\u00e4t und individualisierten Kundenbed\u00fcrfnissen. Zudem teilt er mit uns seine \u00dcberzeugung, dass trotz fortschreitender Digitalisierung und dem Einsatz von Kl-Technologien der pers\u00f6nliche Kontakt im Automobilvertrieb unverzichtbar bleibt.<br \/>Lassen Sie sich inspirieren von einer Episode, die praxisnahe Einblicke und wertvolle Impulse f\u00fcr die Branche verspricht.<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\"4.25.0\" _module_preset=\"default\" theme_builder_area=\"post_content\"][et_pb_column _builder_version=\"4.25.0\" _module_preset=\"default\" type=\"4_4\" theme_builder_area=\"post_content\"][et_pb_text _builder_version=\"4.25.0\" _module_preset=\"default\" theme_builder_area=\"post_content\" link_option_url_new_window=\"on\" link_option_url=\"https:\/\/open.spotify.com\/episode\/0ruYhYxdIGFMezK2oZxJBk?si=Eck2V-aPRTaRGW_8CsH4Rw\" hover_enabled=\"0\" sticky_enabled=\"0\"]<p><strong><a href=\"https:\/\/open.spotify.com\/episode\/0ruYhYxdIGFMezK2oZxJBk?si=Eck2V-aPRTaRGW_8CsH4Rw\" target=\"_blank\" rel=\"noopener\">Jetzt auf Spotify h\u00f6ren &gt;&gt;<\/a><\/strong><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Willkommen zum Podcast \"Zukunft Automobilwirtschaft\"! Wir sprechen \u00fcber die Zukunft des Automobilhandels und die Themen, die die Branche besch\u00e4ftigen. In unseren Episoden sprechen wir \u00fcber M&amp;A-Prozesse, Nachwuchsf\u00f6rderung, neue Gesch\u00e4ftsmodelle und andere wichtige Themen. Unsere renommierten Interviewpartner teilen ihre Erfahrungen und Einblicke in die Branche und zeigen Strategien f\u00fcr die Herausforderungen der Zukunft auf. Wir laden [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3292,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Podcast: ZAW | Zukunft Automobilwirtschaft mit Ralf Rhein - Prudentes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.prudentes.de\/en\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Podcast: ZAW | Zukunft Automobilwirtschaft mit Ralf Rhein - Prudentes\" \/>\n<meta property=\"og:description\" content=\"Willkommen zum Podcast &quot;Zukunft Automobilwirtschaft&quot;! Wir sprechen \u00fcber die Zukunft des Automobilhandels und die Themen, die die Branche besch\u00e4ftigen. In unseren Episoden sprechen wir \u00fcber M&amp;A-Prozesse, Nachwuchsf\u00f6rderung, neue Gesch\u00e4ftsmodelle und andere wichtige Themen. Unsere renommierten Interviewpartner teilen ihre Erfahrungen und Einblicke in die Branche und zeigen Strategien f\u00fcr die Herausforderungen der Zukunft auf. Wir laden [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.prudentes.de\/en\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein\/\" \/>\n<meta property=\"og:site_name\" content=\"Prudentes\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-29T14:19:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-29T14:19:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.prudentes.de\/wp-content\/uploads\/2024\/04\/podcast.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t<meta property=\"og:image:height\" content=\"604\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Prudentes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prudentes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein\"},\"author\":{\"name\":\"Prudentes\",\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/#\\\/schema\\\/person\\\/93b72057083c0c4aa888a2cc8b778587\"},\"headline\":\"Podcast: ZAW | Zukunft Automobilwirtschaft mit Ralf Rhein\",\"datePublished\":\"2024-04-29T14:19:04+00:00\",\"dateModified\":\"2024-04-29T14:19:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein\"},\"wordCount\":510,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.prudentes.de\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/podcast.jpeg\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein\",\"url\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein\",\"name\":\"Podcast: ZAW | Zukunft Automobilwirtschaft mit Ralf Rhein - Prudentes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.prudentes.de\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/podcast.jpeg\",\"datePublished\":\"2024-04-29T14:19:04+00:00\",\"dateModified\":\"2024-04-29T14:19:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/#\\\/schema\\\/person\\\/93b72057083c0c4aa888a2cc8b778587\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein#primaryimage\",\"url\":\"https:\\\/\\\/www.prudentes.de\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/podcast.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.prudentes.de\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/podcast.jpeg\",\"width\":612,\"height\":604},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.prudentes.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Podcast: ZAW | Zukunft Automobilwirtschaft mit Ralf Rhein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/#website\",\"url\":\"https:\\\/\\\/www.prudentes.de\\\/\",\"name\":\"Prudentes\",\"description\":\"Prudentes Management GmbH\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.prudentes.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.prudentes.de\\\/#\\\/schema\\\/person\\\/93b72057083c0c4aa888a2cc8b778587\",\"name\":\"Prudentes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/394a838266da979976a9502a8061fc9690356637af29e0726134ddd925513862?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/394a838266da979976a9502a8061fc9690356637af29e0726134ddd925513862?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/394a838266da979976a9502a8061fc9690356637af29e0726134ddd925513862?s=96&d=mm&r=g\",\"caption\":\"Prudentes\"},\"sameAs\":[\"https:\\\/\\\/wordpress.prudentes.de\"],\"url\":\"https:\\\/\\\/www.prudentes.de\\\/en\\\/author\\\/websiteprudentes\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pod\u00adcast: ZAW | Zukunft Auto\u00admo\u00adbil\u00adwirt\u00adschaft mit Ralf Rhein \u2014 Prudentes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.prudentes.de\/en\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein\/","og_locale":"en_US","og_type":"article","og_title":"Podcast: ZAW | Zukunft Automobilwirtschaft mit Ralf Rhein - Prudentes","og_description":"Willkommen zum Podcast \"Zukunft Automobilwirtschaft\"! Wir sprechen \u00fcber die Zukunft des Automobilhandels und die Themen, die die Branche besch\u00e4ftigen. In unseren Episoden sprechen wir \u00fcber M&amp;A-Prozesse, Nachwuchsf\u00f6rderung, neue Gesch\u00e4ftsmodelle und andere wichtige Themen. Unsere renommierten Interviewpartner teilen ihre Erfahrungen und Einblicke in die Branche und zeigen Strategien f\u00fcr die Herausforderungen der Zukunft auf. Wir laden [&hellip;]","og_url":"https:\/\/www.prudentes.de\/en\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein\/","og_site_name":"Prudentes","article_published_time":"2024-04-29T14:19:04+00:00","article_modified_time":"2024-04-29T14:19:06+00:00","og_image":[{"width":612,"height":604,"url":"https:\/\/www.prudentes.de\/wp-content\/uploads\/2024\/04\/podcast.jpeg","type":"image\/jpeg"}],"author":"Prudentes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Prudentes","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein#article","isPartOf":{"@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein"},"author":{"name":"Prudentes","@id":"https:\/\/www.prudentes.de\/#\/schema\/person\/93b72057083c0c4aa888a2cc8b778587"},"headline":"Podcast: ZAW | Zukunft Automobilwirtschaft mit Ralf Rhein","datePublished":"2024-04-29T14:19:04+00:00","dateModified":"2024-04-29T14:19:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein"},"wordCount":510,"commentCount":0,"image":{"@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein#primaryimage"},"thumbnailUrl":"https:\/\/www.prudentes.de\/wp-content\/uploads\/2024\/04\/podcast.jpeg","inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein","url":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein","name":"Pod\u00adcast: ZAW | Zukunft Auto\u00admo\u00adbil\u00adwirt\u00adschaft mit Ralf Rhein \u2014 Prudentes","isPartOf":{"@id":"https:\/\/www.prudentes.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein#primaryimage"},"image":{"@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein#primaryimage"},"thumbnailUrl":"https:\/\/www.prudentes.de\/wp-content\/uploads\/2024\/04\/podcast.jpeg","datePublished":"2024-04-29T14:19:04+00:00","dateModified":"2024-04-29T14:19:06+00:00","author":{"@id":"https:\/\/www.prudentes.de\/#\/schema\/person\/93b72057083c0c4aa888a2cc8b778587"},"breadcrumb":{"@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein#primaryimage","url":"https:\/\/www.prudentes.de\/wp-content\/uploads\/2024\/04\/podcast.jpeg","contentUrl":"https:\/\/www.prudentes.de\/wp-content\/uploads\/2024\/04\/podcast.jpeg","width":612,"height":604},{"@type":"BreadcrumbList","@id":"https:\/\/www.prudentes.de\/podcast-zaw-zukunft-automobilwirtschaft-mit-ralf-rhein#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.prudentes.de\/"},{"@type":"ListItem","position":2,"name":"Podcast: ZAW | Zukunft Automobilwirtschaft mit Ralf Rhein"}]},{"@type":"WebSite","@id":"https:\/\/www.prudentes.de\/#website","url":"https:\/\/www.prudentes.de\/","name":"Pru\u00adden\u00adtes","description":"Pru\u00adden\u00adtes Manage\u00adment&nbsp;GmbH","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.prudentes.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.prudentes.de\/#\/schema\/person\/93b72057083c0c4aa888a2cc8b778587","name":"Pru\u00adden\u00adtes","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/394a838266da979976a9502a8061fc9690356637af29e0726134ddd925513862?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/394a838266da979976a9502a8061fc9690356637af29e0726134ddd925513862?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/394a838266da979976a9502a8061fc9690356637af29e0726134ddd925513862?s=96&d=mm&r=g","caption":"Prudentes"},"sameAs":["https:\/\/wordpress.prudentes.de"],"url":"https:\/\/www.prudentes.de\/en\/author\/websiteprudentes"}]}},"_links":{"self":[{"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/posts\/3290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/comments?post=3290"}],"version-history":[{"count":4,"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/posts\/3290\/revisions"}],"predecessor-version":[{"id":3297,"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/posts\/3290\/revisions\/3297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/media\/3292"}],"wp:attachment":[{"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/media?parent=3290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/categories?post=3290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prudentes.de\/en\/wp-json\/wp\/v2\/tags?post=3290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}